{"id":452,"date":"2017-06-14T09:24:04","date_gmt":"2017-06-14T08:24:04","guid":{"rendered":"http:\/\/www.clic-formalites.com\/blog\/?p=452"},"modified":"2026-01-28T13:30:39","modified_gmt":"2026-01-28T12:30:39","slug":"journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire","status":"publish","type":"post","link":"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/","title":{"rendered":"Une journ\u00e9e au tribunal de commerce avec un entrepreneur en liquidation judiciaire"},"content":{"rendered":"\n<p><span style=\"font-weight: 400;\">Depuis janvier 2017, le Greffe du Tribunal de commerce a radi\u00e9 pr\u00e8s de 90 000 entreprises du Registre du Commerce et des Soci\u00e9t\u00e9s (RCS).<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Ces entreprises ne peuvent plus faire face aux dettes exigibles avec l\u2019actif disponible. <\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Si elles sont en cessation des paiements et que le redressement judiciaire s\u2019av\u00e8re manifestement impossible.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Le tribunal enclenche alors une proc\u00e9dure de liquidation judiciaire et rend un jugement qui prononce la liquidation d\u00e9finitive de l&rsquo;entreprise.<\/span><\/li>\n<\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">La liquidation judiciaire repose sur l\u2019article <\/span><span style=\"font-weight: 400;\">L641-9-1 du Code Commerce qui dispose que : &nbsp;<\/span><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\">\u00ab I.- Le jugement qui ouvre ou prononce la liquidation judiciaire emporte de plein droit, \u00e0 partir de sa date, dessaisissement pour le d\u00e9biteur de l&rsquo;administration et de la disposition de ses biens m\u00eame de ceux qu&rsquo;il a acquis \u00e0 quel que titre que ce soit tant que la liquidation judiciaire n&rsquo;est pas cl\u00f4tur\u00e9e. Les droits et actions du d\u00e9biteur concernant son patrimoine sont exerc\u00e9s pendant toute la dur\u00e9e de la liquidation judiciaire par le liquidateur \u00bb.<\/span><\/i><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Cette situation, h\u00e9las courante, n\u2019en demeure pas moins m\u00e9connue des entrepreneurs.<\/span><\/p>\n\n\n\n<p style=\"font-style:normal;font-weight:400\">Ainsi, <span style=\"font-weight: 400;\"><a href=\"https:\/\/www.clic-formalites.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Clic Formalit\u00e9s<\/a> vous propose de passer une Journ\u00e9e au Tribunal d\u2019Aix-en Provence pour suivre M. X et assister \u00e0 l\u2019audience d\u2019ouverture de la liquidation judiciaire de son entreprise.<\/span><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\">Les faits :<\/span><\/i><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">M. X est commer\u00e7ant. Il vend du mat\u00e9riel informatique. <\/span><\/li>\n\n\n\n<li style=\"font-style:normal;font-weight:400\"><span style=\"font-weight: 400;\">Son activit\u00e9 s<\/span>e<span style=\"font-weight: 400;\"> situe dans une zone commerciale, o\u00f9 il loue un local \u00e0 cet effet. <\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Jusqu\u2019en 2010, les affaires marchaient bien. <\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Depuis, le chiffre d\u2019affaires a p\u00e9riclit\u00e9.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Aujourd\u2019hui, l\u2019entreprise est en difficult\u00e9 et les dettes s\u2019accumulent : URSSAF, loyers, fournisseurs, salaires des employ\u00e9s, etc.<\/span><\/li>\n<\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">Au vu de sa situation financi\u00e8re, M. X s\u2019est mis en cessation des paiements et a d\u00e9pos\u00e9 le bilan. <\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Son entreprise en difficult\u00e9 s\u2019est trouv\u00e9e dans \u00ab\u2026 l&rsquo;impossibilit\u00e9 de faire face au passif exigible avec son actif disponible \u00bb \u00a0(Article L631-1 du Code de Commerce). <\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">M. X a alors fait une d\u00e9claration de cessation des paiements aupr\u00e8s du Tribunal de Commerce d\u2019Aix-en-Provence dont d\u00e9pend son activit\u00e9.<\/span><\/span><\/li>\n<\/ul>\n\n\n<h2 class=\"wp-block-heading\" id=\"qui-peut-assigner-en-liquidation-judiciairenbspaupres-du-tribunal-competent\"><b>Qui peut assigner en Liquidation judiciaire aupr\u00e8s du tribunal comp\u00e9tent ?<\/b><\/h2>\n\n\n<ul class=\"wp-block-list\">\n<li style=\"font-style:normal;font-weight:400\"><span style=\"font-weight: 400;\">Selon l\u2019article L 640-3 du Code de Commerce <\/span><i><span style=\"font-weight: 400;\">: \u201c<\/span><\/i><i><span style=\"font-weight: 400;\">Lorsqu&rsquo;une personne exer\u00e7ant une activit\u00e9 commerciale ou artisanale, un agriculteur ou toute autre personne physique exer\u00e7ant une activit\u00e9 professionnelle ind\u00e9pendante, (&#8230;) le tribunal peut \u00eatre saisi, (&#8230;) sur l&rsquo;assignation d&rsquo;un <\/span><\/i><b><i>cr\u00e9ancier,<\/i><\/b><i><span style=\"font-weight: 400;\"> quelle que soit la nature de sa cr\u00e9ance, ou <\/span><\/i><b><i>sur requ\u00eate du minist\u00e8re public<\/i><\/b><i><span style=\"font-weight: 400;\">. (&#8230;)\u201d<\/span><\/i><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Ainsi un cr\u00e9ancier ou le Minist\u00e8re Public peut assigner l\u2019entreprise en proc\u00e9dure de liquidation judiciaire (De m\u00eame,<\/span> <span style=\"font-weight: 400;\">pour la proc\u00e9dure en redressement judiciaire). En pratique, l\u2019URSSAF (Unions de Recouvrement des cotisations de S\u00e9curit\u00e9 Sociale et d&rsquo;Allocations Familiales) est souvent \u00e0 l\u2019initiative de la proc\u00e9dure. L<\/span><span style=\"font-weight: 400;\">\u2019assignation doit pr\u00e9ciser la nature et le montant de la cr\u00e9ance. Elle doit \u00e9galement apporter la preuve de \u00a0l\u2019\u00e9tat de cessation des paiements de l\u2019entreprise.<\/span><\/li>\n<\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">Les demandes de placement en liquidation judiciaire doivent \u00e9tablir que le redressement est manifestement impossible.<\/span><\/p>\n\n\n<h2 class=\"wp-block-heading\" id=\"quelle-definition-donner-en-pratique-a-la-cessation-des-paiements\"><b>Quelle d\u00e9finition donner en pratique \u00e0 la cessation des paiements ?<\/b><\/h2>\n\n\n<p><span style=\"font-weight: 400;\">L\u2019article L631-1 du code de commerce dispose que l\u2019\u00e9tat de cessation des paiements est <\/span><i><span style=\"font-weight: 400;\">\u00ab l\u2019impossibilit\u00e9 de faire face au passif exigible avec l\u2019actif disponible. Le d\u00e9biteur qui \u00e9tablit que les r\u00e9serves de cr\u00e9dit ou les moratoires dont il b\u00e9n\u00e9ficie de la part de ses cr\u00e9anciers lui permettent de faire face au passif exigible avec son actif disponible n&rsquo;est pas en cessation des paiements. \u00bb<\/span><\/i><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">En pratique, la cessation des paiements repose sur une notion de tr\u00e9sorerie : Ainsi, l\u2019entreprise peut ou non payer le Jour J ce qu\u2019elle doit au Jour J. <\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Pour savoir si une entreprise est dans la situation d\u2019une cessation des paiements, il faut faire le calcul suivant :<\/span><\/p>\n\n\n\n<p><b>= (Actif disponible &nbsp;&#8211; &nbsp;Passif exigible)<\/b><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Si le solde est positif <\/strong>:<span style=\"font-weight: 400;\"> L\u2019entreprise n\u2019est pas en cessation des paiements. <mark class=\"annotation-text annotation-text-yoast\" id=\"annotation-text-7d1b2b5d-07fa-4125-8e6d-744de0cc61b3\">Elle peut donc s\u2019acquitter de son \u00ab passif exigible \u00bb.<\/mark> L\u2019entreprise est en mesure de r\u00e9tablir une situation comptable et financi\u00e8re \u00e9quilibr\u00e9e.<\/span><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Si le solde est n\u00e9gatif<\/strong> : <span style=\"font-weight: 400;\">L\u2019entreprise est en cessation des paiements.<\/span><\/li>\n<\/ul>\n\n\n\n<p><b>Pour conna\u00eetre l\u2019 \u201cactif disponible\u201d<\/b><b><i> = (<\/i><\/b><b>Actif liquide + Actif r\u00e9alisable)<\/b><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">&#8211; <\/span><b>L\u2019actif liquide : <\/b><span style=\"font-weight: 400;\">Sommes r\u00e9alisables \u00e0 tr\u00e8s court terme (Sommes en caisse, soldes cr\u00e9diteurs provisoires des comptes bancaires \u00e0 vue, etc).<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">&#8211; <\/span><b>L\u2019actif r\u00e9alisable : <\/b><span style=\"font-weight: 400;\">Sommes qui seront rapidement en liquidit\u00e9.<\/span><\/p>\n\n\n\n<p style=\"font-style:normal;font-weight:400\"><strong>L&rsquo;analyse comptable exclut de l\u2019actif disponible<\/strong> les biens que l&rsquo;entreprise ne peut pas c\u00e9der \u00e0 court terme (prix d\u2019acquisition du fonds de commerce, co\u00fbt des travaux effectu\u00e9s dans les locaux, etc.).<\/p>\n\n\n\n<p><b>Pour conna\u00eetre le \u201cpassif exigible\u201d = La somme des dettes (De nature civile ou commerciale)<\/b><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><b>Dettes certaines <\/b><span style=\"font-weight: 400;\">: Dettes qui ne font pas l\u2019objet de contestation.<\/span><\/li>\n\n\n\n<li><b>Dettes liquides <\/b><span style=\"font-weight: 400;\">: Dettes dont le montant peut \u00eatre estim\u00e9 en mon\u00e9taire.<\/span><\/li>\n\n\n\n<li><b>Dettes Exigibles <\/b><span style=\"font-weight: 400;\">: Dettes dont le terme est \u00e9chu.<\/span><\/li>\n<\/ul>\n\n\n\n<p style=\"font-style:normal;font-weight:400\"><b>L\u2019analyse comptable exclut du passif exigible <\/b>les cr\u00e9ances litigieuses ou celles qui ne pr\u00e9sentent pas l&rsquo;un des trois caract\u00e8res pr\u00e9cit\u00e9s.<\/p>\n\n\n<h2 class=\"wp-block-heading\" id=\"qui-peut-faire-lobjet-dune-cessation-des-paiements\"><b>Qui peut faire l\u2019objet d\u2019une cessation des paiements ?<\/b><\/h2>\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Toute personne physique exer\u00e7ant une activit\u00e9 commerciale, artisanale, lib\u00e9rale ou agricole<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Un Entrepreneur Individuel \u00e0 Responsabilit\u00e9 Limit\u00e9e (EIRL)<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Un auto-entrepreneur<\/span><\/li>\n\n\n\n<li style=\"font-style:normal;font-weight:400\">Toute personne physique exer\u00e7ant une activit\u00e9 professionnelle ind\u00e9pendante (Y compris une profession lib\u00e9rale)<\/li>\n\n\n\n<li style=\"font-style:normal;font-weight:400\">Toute personne morale de droit priv\u00e9, notamment : Les soci\u00e9t\u00e9s commerciales pluripersonnelles \u00a0= \u00a0Les Soci\u00e9t\u00e9s Anonymes (SA), les Soci\u00e9t\u00e9s Anonymes \u00e0 Responsabilit\u00e9 Limit\u00e9e (SARL) et les Soci\u00e9t\u00e9s par Actions Simplifi\u00e9e (SAS), les Soci\u00e9t\u00e9s Civiles de Gestion et \u00a0Immobili\u00e8res, etc.<\/li>\n<\/ul>\n\n\n\n<p><i><span style=\"font-weight: 400;\">Mais que va-t-il se passer concr\u00e8tement pour M. X apr\u00e8s sa d\u00e9claration de cessation des paiements ?<\/span><\/i><\/p>\n\n\n<h2 class=\"wp-block-heading\" id=\"au-tribunal-de-commerce\"><b>Au Tribunal de Commerce<\/b><\/h2>\n\n\n<p><i><span style=\"font-weight: 400;\">Nous sommes un mardi.<br><\/span><\/i><i><span style=\"font-weight: 400;\">Et comme tous les mardis, au Tribunal de Commerce d\u2019Aix-en-Provence a lieu l\u2019audience relative aux liquidations judiciaires. Il est 8h30, la salle des actes commence \u00e0 se remplir : Avocats, artisans, commer\u00e7ants, bailleurs, d\u00e9biteurs etc.<br><\/span><\/i><i><span style=\"font-weight: 400;\">Tous attendent l\u2019ouverture de l\u2019audience. &nbsp;<\/span><\/i><span style=\"font-weight: 400;\"><br><\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">&#8211; M. X : \u201c <\/span><i><span style=\"font-weight: 400;\">J\u2019ai \u00e9t\u00e9 convoqu\u00e9 \u00e0 une audience par le Tribunal de Commerce. <\/span><\/i><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\">Plus rien n\u2019allait au niveau de l\u2019activit\u00e9. Les dettes se sont accumul\u00e9es, les cr\u00e9anciers se sont faits pressants, mon bailleur au d\u00e9part compr\u00e9hensif, ne l\u2019\u00e9tait plus. J\u2019avais 3 mois de loyers en retard, sans compter tout le reste \u2026 J\u2019\u00e9tais d\u00e9biteur sur quasiment tous les plans. J\u2019ai donc demand\u00e9 \u00e0 mon comptable de me faire un bilan de la situation financi\u00e8re de l\u2019entreprise. Le r\u00e9sultat \u00e9tait sans appel : L\u2019entreprise \u00e9tait en cessation des paiements. On doit mettre la cl\u00e9 sous la porte.<\/span><\/i><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\">En tant que d\u00e9biteur, j\u2019avais 45 jours pour d\u00e9poser une d\u00e9claration de cessation de paiements \u00e0 compter de la date de cessation des paiements. <\/span><\/i><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\">Et en tant que commer\u00e7ant, il fallait que je m\u2019adresse au greffe du Tribunal de Commerce. \u00c9tant donn\u00e9 mes relations tendues avec les diff\u00e9rents cr\u00e9anciers, j\u2019ai \u00e9cart\u00e9 la proc\u00e9dure de conciliation. J\u2019ai demand\u00e9 \u00e0 ce que mon entreprise soit mise en redressement judiciaire. Et 15 jours, apr\u00e8s je suis au Tribunal de Commerce pour l\u2019audience.\u201c<\/span><\/i><\/p>\n\n\n<h3 class=\"wp-block-heading\" id=\"pour-rappel\">Pour rappel :<\/h3>\n\n\n<p><span style=\"font-weight: 400;\">&#8211; Tout d\u00e9biteur, personne physique ou dirigeant, qui oublie sciemment d\u2019effectuer la d\u00e9claration de cessation des paiements risque alors des sanctions, principalement une interdiction de g\u00e9rer.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">&#8211; M\u00eame si un cr\u00e9ancier saisit d\u00e9j\u00e0 le tribunal pour demander l&rsquo;ouverture d&rsquo;un redressement ou d&rsquo;une liquidation, le d\u00e9biteur doit tout de m\u00eame d\u00e9clarer sa cessation des paiements.<\/span><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\">Retour au Tribunal de Commerce d\u2019Aix-en-Provence.<\/span><\/i><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\">Les portes s\u2019ouvrent et le greffier appara\u00eet. Il demande \u00e0 tous d\u2019entrer dans la salle.<\/span><\/i><\/p>\n\n\n<h3 class=\"wp-block-heading\" id=\"sont-toujours-presents-a-laudience-du-tribunal-de-commerce\">Sont toujours pr\u00e9sents \u00e0 l\u2019audience du Tribunal de Commerce :<\/h3>\n\n\n<ul class=\"wp-block-list\">\n<li style=\"font-style:normal;font-weight:400\"><b>Le Pr\u00e9sident du Tribunal de Commerce et ses 2 assesseurs<\/b><span style=\"font-weight: 400;\">. <\/span>La choix se fait parmi<span style=\"font-weight: 400;\"> des commer\u00e7ants ou des dirigeants d&rsquo;entreprises. B\u00e9n\u00e9voles, ces juges consulaires ne sont alors pas des juges professionnels.<\/span><\/li>\n\n\n\n<li><b>Le greffier du Tribunal <\/b><span style=\"font-weight: 400;\">en charge de prendre<\/span> <span style=\"font-weight: 400;\">en note tout ce qu\u2019il se dit au cours de l\u2019audience.<\/span><\/li>\n\n\n\n<li><b>Le minist\u00e8re public <\/b><span style=\"font-weight: 400;\">repr\u00e9sent\u00e9 par un Magistrat du Parquet, en charge de garantir de l\u2019ordre public \u00e9conomique<\/span><\/li>\n\n\n\n<li><b>Les liquidateurs judiciaires<\/b><span style=\"font-weight: 400;\"> en charge des diff\u00e9rentes affaires.<\/span><\/li>\n\n\n\n<li><b>Les repr\u00e9sentants de la soci\u00e9t\u00e9 en liquidation.<\/b><\/li>\n<\/ul>\n\n\n<h3 class=\"wp-block-heading\" id=\"un-appel-est-effectue\">Un appel est effectu\u00e9 :<\/h3>\n\n\n<ul class=\"wp-block-list\">\n<li><b>La soci\u00e9t\u00e9 est pr\u00e9sente avec un dossier complet :<\/b><span style=\"font-weight: 400;\"> L\u2019affaire est trait\u00e9e le jour dit.<\/span><\/li>\n\n\n\n<li><b>La soci\u00e9t\u00e9 est absente :<\/b><span style=\"font-weight: 400;\"> L\u2019audience est repouss\u00e9e ult\u00e9rieurement.<\/span><\/li>\n\n\n\n<li><b>La soci\u00e9t\u00e9 est pr\u00e9sente mais demande un d\u00e9lai :<\/b><span style=\"font-weight: 400;\"> Celui-ci est ou non accept\u00e9 par le Pr\u00e9sident.<\/span><\/li>\n<\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">Une fois ce premier appel fini, le greffier invite chacun \u00e0 sortir.<br>Alors, apr\u00e8s quelques minutes, il r\u00e9appara\u00eet et invite la premi\u00e8re soci\u00e9t\u00e9 \u00e0 se pr\u00e9senter.<\/span><\/p>\n\n\n\n<p style=\"font-style:normal;font-weight:400\">M. X entre alors dans la salle d\u2019audience.<\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Il n\u2019a pas d\u00e9sir\u00e9 se faire accompagner d\u2019un avocat ni de son expert comptable.<br>Le tribunal entend le dirigeant et le repr\u00e9sentant des salari\u00e9s \u00e0 huis clos, en chambre du conseil.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Apr\u00e8s une heure d\u2019audience, M. X sort.<\/span><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\">\u00ab C\u2019\u00e9tait assez impressionnant. Il y avait beaucoup de personnes pr\u00e9sentes. Le Pr\u00e9sident du Tribunal m\u2019a demand\u00e9 des informations sur l\u2019entreprise, sur son activit\u00e9. : Paiements des cr\u00e9anciers, d\u00e9tails techniques et si une conciliation avait pu \u00eatre obtenue.<\/span><\/i><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\">Le repr\u00e9sentant du Procureur de la R\u00e9publique a pris la parole. Il a estim\u00e9 qu\u2019au vu de l\u2019\u00e9tat de mes finances et de la situation de mon entreprise, on devait \u00e9carter la proc\u00e9dure de redressement judiciaire et pr\u00e9f\u00e9rer la proc\u00e9dure de liquidation judiciaire \u00bb<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p>\n\n\n<h3 class=\"wp-block-heading\" id=\"pour-rappel-le-tribunal-choisit-la-procedure-de-liquidation-judiciaire-si-deux-conditions-se-reunissent\">Pour rappel, le tribunal choisit la proc\u00e9dure de liquidation judiciaire si deux conditions se r\u00e9unissent :<\/h3>\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">L\u2019entreprise est en cessation des paiements.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Le redressement est manifestement impossible.<\/span><\/li>\n<\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">La liquidation judiciaire a pour but de mettre fin \u00e0 l\u2019activit\u00e9 de l\u2019entreprise, mais aussi, de r\u00e9aliser son patrimoine par cession globale ou par une liquidation s\u00e9par\u00e9e de ses biens et de ses droits.<\/span><\/p>\n\n\n\n<p style=\"font-style:normal;font-weight:400\"><i style=\"font-size: 1rem;\">M.X : \u00ab &nbsp;Le Pr\u00e9sident a ensuite conclu et m\u2019a dit que mon entreprise allait faire l\u2019objet d\u2019une proc\u00e9dure de liquidation judiciaire. Il a \u00e9galement affirm\u00e9 que la poursuite de l\u2019activit\u00e9 de l\u2019entreprise \u00e9tait autoris\u00e9e pour une p\u00e9riode de 3 mois pour faciliter une solution de cession. Le Pr\u00e9sident a aussi indiqu\u00e9 que cette ouverture de la proc\u00e9dure de liquidation judiciaire a plusieurs impacts. Par exemple, <\/i><i style=\"font-size: 1rem;\">en tant que le d\u00e9biteur, on ne peut plus administrer les biens de l\u2019entreprise tant que la liquidation n\u2019est pas close ainsi que le gel des poursuites contre l\u2019entreprise et la nomination d\u2019un juge commissaire par le tribunal. Il veillera au bon d\u00e9roulement de la proc\u00e9dure. Un liquidateur judiciaire est aussi nomm\u00e9 et il &nbsp;se substitue au chef d\u2019entreprise\u00bb.<\/i><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\">Le tribunal a donn\u00e9 3 mois au liquidateur judiciaire pour tout remettre en ordre. <\/span><\/i><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n\n\n\n<p style=\"font-style:normal;font-weight:400\">Pass\u00e9 ce d\u00e9lai, M. X sera \u00e0 nouveau convoqu\u00e9 par le Tribunal.<br><span style=\"font-weight: 400;\">Il sera fix\u00e9 <\/span>alors<span style=\"font-weight: 400;\"> sur son sort et celui de son entreprise.<br>Cette audience sera \u00e9galement importante pour le maintien de l\u2019activit\u00e9 de l\u2019entreprise.<br>Le liquidateur aura alors 3 mois pour trouver un repreneur.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Clic formalit\u00e9s sera l\u00e0 pour le d\u00e9nouement de cette proc\u00e9dure de liquidation judiciaire.<\/span><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-light-color has-accent-3-background-color has-text-color has-background has-link-color has-custom-font-size wp-element-button\" href=\"https:\/\/www.clic-formalites.com\/fermeture-entreprise\" style=\"font-size:clamp(0.875rem, 0.875rem + ((1vw - 0.2rem) * 0.227), 1rem);\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Fermer son entreprise <\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p><em><strong>Sources :\u00a0<\/strong><\/em><br><a href=\"https:\/\/www.legifrance.gouv.fr\"><em>https:\/\/www.legifrance.gouv.fr<\/em><\/a><br><a href=\"https:\/\/www.infogreffe.fr\/\"><em>https:\/\/www.infogreffe.fr\/<\/em><\/a><br><a href=\"http:\/\/www.justice.gouv.fr\/\"><em>http:\/\/www.justice.gouv.fr\/<\/em><\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis janvier 2017, le Greffe du Tribunal de commerce a radi&eacute; pr&egrave;s de 90 000 entreprises du Registre du Commerce et des Soci&eacute;t&eacute;s (RCS). La liquidation judiciaire repose sur l&rsquo;article L641-9-1 du Code Commerce qui dispose que : &nbsp; &laquo; I.- Le jugement qui ouvre ou prononce la liquidation judiciaire emporte de plein droit, &agrave; [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":735,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,51,32],"tags":[],"class_list":["post-452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guide-a-lentrepreneur","category-les-dossiers","category-liquidation-de-societe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un exemple concret de liquidation judiciaire<\/title>\n<meta name=\"description\" content=\"Quelle est la proc\u00e9dure d\u2019ouverture d\u2019une liquidation judiciaire au tribunal ? Journ\u00e9e au tribunal de commerce avec un entrepreneur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un exemple concret de liquidation judiciaire\" \/>\n<meta property=\"og:description\" content=\"Quelle est la proc\u00e9dure d\u2019ouverture d\u2019une liquidation judiciaire au tribunal ? Journ\u00e9e au tribunal de commerce avec un entrepreneur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Clic Formalit\u00e9s, Le Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/search\/top?q=clicformalits\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-14T08:24:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T12:30:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.clic-formalites.com\/blog\/wp-content\/uploads\/2017\/06\/025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Doriane S.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Doriane S.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\\\/\"},\"author\":{\"name\":\"Doriane S.\",\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/#\\\/schema\\\/person\\\/0a5af902de850798958dcc5ec7a60293\"},\"headline\":\"Une journ\u00e9e au tribunal de commerce avec un entrepreneur en liquidation judiciaire\",\"datePublished\":\"2017-06-14T08:24:04+00:00\",\"dateModified\":\"2026-01-28T12:30:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\\\/\"},\"wordCount\":1982,\"publisher\":{\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/025.png\",\"articleSection\":[\"Guide de l'Entrepreneur\",\"Les Dossiers\",\"Liquidation de Soci\u00e9t\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\\\/\",\"url\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\\\/\",\"name\":\"Un exemple concret de liquidation judiciaire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/025.png\",\"datePublished\":\"2017-06-14T08:24:04+00:00\",\"dateModified\":\"2026-01-28T12:30:39+00:00\",\"description\":\"Quelle est la proc\u00e9dure d\u2019ouverture d\u2019une liquidation judiciaire au tribunal ? Journ\u00e9e au tribunal de commerce avec un entrepreneur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/025.png\",\"contentUrl\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/025.png\",\"width\":1170,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une journ\u00e9e au tribunal de commerce avec un entrepreneur en liquidation judiciaire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/\",\"name\":\"Clic Formalit\u00e9s, Le Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/#organization\",\"name\":\"Clic Formalit\u00e9s, Le Blog\",\"url\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/clic-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/clic-logo.png\",\"width\":884,\"height\":329,\"caption\":\"Clic Formalit\u00e9s, Le Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/search\\\/top?q=clicformalits\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/clic-formalits\\\/posts\\\/?feedView=all\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/#\\\/schema\\\/person\\\/0a5af902de850798958dcc5ec7a60293\",\"name\":\"Doriane S.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6e9a8743b1659d0e2554de64a478a08aa5d2eed9e44b7b6a27bba7301ce3f71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6e9a8743b1659d0e2554de64a478a08aa5d2eed9e44b7b6a27bba7301ce3f71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6e9a8743b1659d0e2554de64a478a08aa5d2eed9e44b7b6a27bba7301ce3f71?s=96&d=mm&r=g\",\"caption\":\"Doriane S.\"},\"url\":\"https:\\\/\\\/www.clic-formalites.com\\\/blog\\\/author\\\/doriane\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un exemple concret de liquidation judiciaire","description":"Quelle est la proc\u00e9dure d\u2019ouverture d\u2019une liquidation judiciaire au tribunal ? Journ\u00e9e au tribunal de commerce avec un entrepreneur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/","og_locale":"fr_FR","og_type":"article","og_title":"Un exemple concret de liquidation judiciaire","og_description":"Quelle est la proc\u00e9dure d\u2019ouverture d\u2019une liquidation judiciaire au tribunal ? Journ\u00e9e au tribunal de commerce avec un entrepreneur.","og_url":"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/","og_site_name":"Clic Formalit\u00e9s, Le Blog","article_publisher":"https:\/\/www.facebook.com\/search\/top?q=clicformalits","article_published_time":"2017-06-14T08:24:04+00:00","article_modified_time":"2026-01-28T12:30:39+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/www.clic-formalites.com\/blog\/wp-content\/uploads\/2017\/06\/025.png","type":"image\/png"}],"author":"Doriane S.","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Doriane S.","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/#article","isPartOf":{"@id":"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/"},"author":{"name":"Doriane S.","@id":"https:\/\/www.clic-formalites.com\/blog\/#\/schema\/person\/0a5af902de850798958dcc5ec7a60293"},"headline":"Une journ\u00e9e au tribunal de commerce avec un entrepreneur en liquidation judiciaire","datePublished":"2017-06-14T08:24:04+00:00","dateModified":"2026-01-28T12:30:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/"},"wordCount":1982,"publisher":{"@id":"https:\/\/www.clic-formalites.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.clic-formalites.com\/blog\/wp-content\/uploads\/2017\/06\/025.png","articleSection":["Guide de l'Entrepreneur","Les Dossiers","Liquidation de Soci\u00e9t\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/","url":"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/","name":"Un exemple concret de liquidation judiciaire","isPartOf":{"@id":"https:\/\/www.clic-formalites.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/#primaryimage"},"image":{"@id":"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.clic-formalites.com\/blog\/wp-content\/uploads\/2017\/06\/025.png","datePublished":"2017-06-14T08:24:04+00:00","dateModified":"2026-01-28T12:30:39+00:00","description":"Quelle est la proc\u00e9dure d\u2019ouverture d\u2019une liquidation judiciaire au tribunal ? Journ\u00e9e au tribunal de commerce avec un entrepreneur.","breadcrumb":{"@id":"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/#primaryimage","url":"https:\/\/www.clic-formalites.com\/blog\/wp-content\/uploads\/2017\/06\/025.png","contentUrl":"https:\/\/www.clic-formalites.com\/blog\/wp-content\/uploads\/2017\/06\/025.png","width":1170,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/www.clic-formalites.com\/blog\/journee-tribunal-de-commerce-entrepreneur-liquidation-judiciaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.clic-formalites.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Une journ\u00e9e au tribunal de commerce avec un entrepreneur en liquidation judiciaire"}]},{"@type":"WebSite","@id":"https:\/\/www.clic-formalites.com\/blog\/#website","url":"https:\/\/www.clic-formalites.com\/blog\/","name":"Clic Formalit\u00e9s, Le Blog","description":"","publisher":{"@id":"https:\/\/www.clic-formalites.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clic-formalites.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.clic-formalites.com\/blog\/#organization","name":"Clic Formalit\u00e9s, Le Blog","url":"https:\/\/www.clic-formalites.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.clic-formalites.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.clic-formalites.com\/blog\/wp-content\/uploads\/2026\/01\/clic-logo.png","contentUrl":"https:\/\/www.clic-formalites.com\/blog\/wp-content\/uploads\/2026\/01\/clic-logo.png","width":884,"height":329,"caption":"Clic Formalit\u00e9s, Le Blog"},"image":{"@id":"https:\/\/www.clic-formalites.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/search\/top?q=clicformalits","https:\/\/www.linkedin.com\/company\/clic-formalits\/posts\/?feedView=all"]},{"@type":"Person","@id":"https:\/\/www.clic-formalites.com\/blog\/#\/schema\/person\/0a5af902de850798958dcc5ec7a60293","name":"Doriane S.","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d6e9a8743b1659d0e2554de64a478a08aa5d2eed9e44b7b6a27bba7301ce3f71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d6e9a8743b1659d0e2554de64a478a08aa5d2eed9e44b7b6a27bba7301ce3f71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6e9a8743b1659d0e2554de64a478a08aa5d2eed9e44b7b6a27bba7301ce3f71?s=96&d=mm&r=g","caption":"Doriane S."},"url":"https:\/\/www.clic-formalites.com\/blog\/author\/doriane\/"}]}},"_links":{"self":[{"href":"https:\/\/www.clic-formalites.com\/blog\/wp-json\/wp\/v2\/posts\/452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clic-formalites.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clic-formalites.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clic-formalites.com\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clic-formalites.com\/blog\/wp-json\/wp\/v2\/comments?post=452"}],"version-history":[{"count":1,"href":"https:\/\/www.clic-formalites.com\/blog\/wp-json\/wp\/v2\/posts\/452\/revisions"}],"predecessor-version":[{"id":1331,"href":"https:\/\/www.clic-formalites.com\/blog\/wp-json\/wp\/v2\/posts\/452\/revisions\/1331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clic-formalites.com\/blog\/wp-json\/wp\/v2\/media\/735"}],"wp:attachment":[{"href":"https:\/\/www.clic-formalites.com\/blog\/wp-json\/wp\/v2\/media?parent=452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clic-formalites.com\/blog\/wp-json\/wp\/v2\/categories?post=452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clic-formalites.com\/blog\/wp-json\/wp\/v2\/tags?post=452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}